{"id":6960,"date":"2024-12-20T11:29:31","date_gmt":"2024-12-20T10:29:31","guid":{"rendered":"https:\/\/cafesbatalla.com\/?p=6960"},"modified":"2025-09-18T12:16:51","modified_gmt":"2025-09-18T10:16:51","slug":"xavier-batalla-al-llibre-gent-dempresa","status":"publish","type":"post","link":"https:\/\/cafesbatalla.com\/ca\/xavier-batalla-en-el-libro-gent-dempresa\/","title":{"rendered":"Xavier Batalla al llibre &#039;Gent d&#039;empresa&#039; de La Ma\u00f1ana"},"content":{"rendered":"<p>Un dibuix d&#039;Ermengol de <strong>Xavier Batalla<\/strong>, mestre torrador i tercera generaci\u00f3 de Caf\u00e9s Batalla, forma part del llibre <strong>&quot;Gent d&#039;empresa. Retrats de l&#039;Ermengol<\/strong>\u201d editat pel diari <strong>EL MAT\u00cd,<\/strong> en el marc del seu 85\u00e8 aniversari, i que \u00e9s solidari amb la <strong>Associaci\u00f3 Contra el C\u00e0ncer a Lleida<\/strong>, entitat que rebr\u00e0 tots els beneficis que produeixi la venda del llibre.<\/p>\n<p>L&#039;artista lleidat\u00e0 <strong>Paco Ermengol<\/strong> ha dibuixat un conjunt d&#039;empresaris i empres\u00e0ries del territori, encap\u00e7alats pel president editor del diari, Jordi Solana Aguilera, i afegint tamb\u00e9 el conseller d&#039;Agricultura \u00d2scar Ordeig, el president de la Diputaci\u00f3 Joan Talarn, i l&#039;alcalde de Lleida F\u00e8lix Larrosa com a representants institucionals, a m\u00e9s d&#039;un dibuix d&#039;ell mateix.<\/p>\n<p><strong>Xavier Batalla<\/strong> ha manifestat que &quot;agraeixo al MAT\u00cd ia Ermengol aquest gest amb mi. \u00c9s un orgull per a mi i per a Caf\u00e9s Batalla formar part d&#039;aquesta compilaci\u00f3 de persones de les empreses de Lleida. Per a nosaltres \u00e9s un est\u00edmul i un reconeixement a la tasca que fem cada dia&quot; i afegeix &quot;aix\u00f2 vol dir que ho fem b\u00e9, per tant, continua<\/p>\n<p>Podeu ampliar la not\u00edcia a <a href=\"https:\/\/lamanyana.cat\/el-llibre-gent-dempresa-clou-el-85e-aniversari-de-la-manana\/\" target=\"_blank\" rel=\"noopener\">EL MAT\u00cd<\/a><\/p>\n<p class=\"p7\"><span class=\"s3\"><a href=\"https:\/\/lamanyana.cat\/el-llibre-gent-dempresa-clou-el-85e-aniversari-de-la-manana\/\" target=\"_blank\" rel=\"noopener\">https:\/\/lamanyana.cat\/el-llibre-gent-dempresa-clou-el-85e-aniversari-de-la-manana\/<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-6970 aligncenter\" src=\"https:\/\/cafesbatalla.com\/wp-content\/uploads\/RETRAT-JAVTO-llibre.jpg\" alt=\"\" width=\"1080\" height=\"1489\" srcset=\"https:\/\/cafesbatalla.com\/wp-content\/uploads\/RETRAT-JAVTO-llibre.jpg 1080w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/RETRAT-JAVTO-llibre-768x1059.jpg 768w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/RETRAT-JAVTO-llibre-29x40.jpg 29w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/RETRAT-JAVTO-llibre-44x60.jpg 44w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/RETRAT-JAVTO-llibre-58x80.jpg 58w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><br \/>\n<img decoding=\"async\" class=\"alignnone size-full wp-image-6964\" src=\"https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla.jpg 1920w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla-768x432.jpg 768w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla-1536x864.jpg 1536w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla-40x23.jpg 40w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla-60x34.jpg 60w, https:\/\/cafesbatalla.com\/wp-content\/uploads\/LIBRO-javito-batalla-80x45.jpg 80w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Un dibujo de Ermengol de Xavier Batalla, maestro tostador y tercera generaci\u00f3n de Caf\u00e9s Batalla, forma parte del libro \u201cGent d&#8217;empresa. Retrats de l&#8217;Ermengol\u201d editado por el diario LA MA\u00d1ANA, en el marco de su 85.\u00ba cumplea\u00f1os, y que es solidario con la Asociaci\u00f3n Contra el C\u00e1ncer en Lleida, entidad que recibir\u00e1 todo los beneficios [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[353],"tags":[],"class_list":["post-6960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noves-noticies"],"_links":{"self":[{"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/posts\/6960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/comments?post=6960"}],"version-history":[{"count":0,"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/posts\/6960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/media\/6961"}],"wp:attachment":[{"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/media?parent=6960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/categories?post=6960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cafesbatalla.com\/ca\/wp-json\/wp\/v2\/tags?post=6960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}